{"id":2810,"date":"2015-03-16T14:22:34","date_gmt":"2015-03-16T13:22:34","guid":{"rendered":"http:\/\/whatfoodcan.com\/?post_type=project&#038;p=2810"},"modified":"2025-05-08T20:31:35","modified_gmt":"2025-05-08T18:31:35","slug":"semillas-de-chia","status":"publish","type":"project","link":"https:\/\/whatfoodcan.com\/es\/project\/semillas-de-chia\/","title":{"rendered":"Semillas de Ch\u00eda"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ch\u00eda semillas \u2013 fuerza y resistencia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los guerreros mayas y aztecas siempre llevaban semillas de ch\u00eda encima. Debido a su alto valor energ\u00e9tico y nutritivo los hombres aguantaban mejor las largas caminatas. Estas &nbsp;super semillas necesitan el c\u00e1lido clima de America Central y del Sur para crecer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por sus propiedades sobresalientes no es de extra\u00f1ar que hayan conquistado las tiendas de alimentaci\u00f3n natural r\u00e1pidamente en todo el mundo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contienen muchas vitaminas, prote\u00ednas, fibra soluble, antioxidantes, minerales y amino\u00e1cidos en alta concentraci\u00f3n. Los \u00e1cidos grasos Omega 3 y Omega 6 abundan en una proporci\u00f3n excelente. Otros tipos de verdura o fruta se quedan bastante atr\u00e1s en comparaci\u00f3n con estas semillas \u201emaravillosas\u201c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las semillas de ch\u00eda bajan la presi\u00f3n sangu\u00ednea y protegen el coraz\u00f3n. (Las personas con la tensi\u00f3n baja deber\u00edan consultar su m\u00e9dico antes de tomarlas.) Ayudan a reducir peso, ya que con su capacidad de absorci\u00f3n de l\u00edquido provocan una sensaci\u00f3n de saciedad. De forma muy suave, ayudan en la limpieza de los intestinos. Detalle interesante para diab\u00e9ticos: las semillas de ch\u00eda ayudan a estabilizar el nivel de az\u00facar en la sangre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eCh\u00eda fresca\u201c es una bebida tradicional en Am\u00e9rica Central y Sur de M\u00e9xico: poner una cucharadita de semillas durante 20 \u2013 30 minutos en remojo (una taza de agua). Remover de vez en cuando para evitar grumos. Sazonar la masa gelatinosa y suave con un poco de miel y lim\u00f3n (o lima) y beber. Es totalmente natural, refrescante, simple y est\u00e1 llena de energ\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00f1adir las semillas de ch\u00eda molidas a un zumo de fruta o un smoothie es muy favorable.<\/p>\n","protected":false},"featured_media":2811,"parent":0,"template":"","meta":{"_acf_changed":false},"skill":[23],"class_list":["post-2810","project","type-project","status-publish","has-post-thumbnail","hentry","skill-cereales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semillas de Ch\u00eda | What food can<\/title>\n<meta name=\"description\" content=\"Las semillas de ch\u00eda contienen muchas vitaminas, prote\u00ednas, fibra soluble, antioxidantes, minerales y amino\u00e1cidos en alta concentraci\u00f3n. Los \u00e1cidos grasos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whatfoodcan.com\/es\/project\/semillas-de-chia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semillas de Ch\u00eda | What food can\" \/>\n<meta property=\"og:description\" content=\"Las semillas de ch\u00eda contienen muchas vitaminas, prote\u00ednas, fibra soluble, antioxidantes, minerales y amino\u00e1cidos en alta concentraci\u00f3n. Los \u00e1cidos grasos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whatfoodcan.com\/es\/project\/semillas-de-chia\/\" \/>\n<meta property=\"og:site_name\" content=\"What Food Can\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-08T18:31:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2015\/03\/semillasdechia_whatfoodcan.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/semillas-de-chia\\\/\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/semillas-de-chia\\\/\",\"name\":\"Semillas de Ch\u00eda | What food can\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/semillas-de-chia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/semillas-de-chia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/semillasdechia_whatfoodcan.jpg\",\"datePublished\":\"2015-03-16T13:22:34+00:00\",\"dateModified\":\"2025-05-08T18:31:35+00:00\",\"description\":\"Las semillas de ch\u00eda contienen muchas vitaminas, prote\u00ednas, fibra soluble, antioxidantes, minerales y amino\u00e1cidos en alta concentraci\u00f3n. Los \u00e1cidos grasos\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/semillas-de-chia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/semillas-de-chia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/semillasdechia_whatfoodcan.jpg\",\"contentUrl\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/semillasdechia_whatfoodcan.jpg\",\"width\":750,\"height\":570},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#website\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/\",\"name\":\"What Food Can\",\"description\":\"What Food Can do for You\",\"publisher\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whatfoodcan.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#organization\",\"name\":\"What Food Can\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/whatfoodcan-logo.png\",\"contentUrl\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/whatfoodcan-logo.png\",\"width\":200,\"height\":200,\"caption\":\"What Food Can\"},\"image\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semillas de Ch\u00eda | What food can","description":"Las semillas de ch\u00eda contienen muchas vitaminas, prote\u00ednas, fibra soluble, antioxidantes, minerales y amino\u00e1cidos en alta concentraci\u00f3n. Los \u00e1cidos grasos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whatfoodcan.com\/es\/project\/semillas-de-chia\/","og_locale":"es_ES","og_type":"article","og_title":"Semillas de Ch\u00eda | What food can","og_description":"Las semillas de ch\u00eda contienen muchas vitaminas, prote\u00ednas, fibra soluble, antioxidantes, minerales y amino\u00e1cidos en alta concentraci\u00f3n. Los \u00e1cidos grasos","og_url":"https:\/\/whatfoodcan.com\/es\/project\/semillas-de-chia\/","og_site_name":"What Food Can","article_modified_time":"2025-05-08T18:31:35+00:00","og_image":[{"width":750,"height":570,"url":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2015\/03\/semillasdechia_whatfoodcan.jpg","type":"image\/jpeg"}],"twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/whatfoodcan.com\/es\/project\/semillas-de-chia\/","url":"https:\/\/whatfoodcan.com\/es\/project\/semillas-de-chia\/","name":"Semillas de Ch\u00eda | What food can","isPartOf":{"@id":"https:\/\/whatfoodcan.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whatfoodcan.com\/es\/project\/semillas-de-chia\/#primaryimage"},"image":{"@id":"https:\/\/whatfoodcan.com\/es\/project\/semillas-de-chia\/#primaryimage"},"thumbnailUrl":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2015\/03\/semillasdechia_whatfoodcan.jpg","datePublished":"2015-03-16T13:22:34+00:00","dateModified":"2025-05-08T18:31:35+00:00","description":"Las semillas de ch\u00eda contienen muchas vitaminas, prote\u00ednas, fibra soluble, antioxidantes, minerales y amino\u00e1cidos en alta concentraci\u00f3n. Los \u00e1cidos grasos","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whatfoodcan.com\/es\/project\/semillas-de-chia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whatfoodcan.com\/es\/project\/semillas-de-chia\/#primaryimage","url":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2015\/03\/semillasdechia_whatfoodcan.jpg","contentUrl":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2015\/03\/semillasdechia_whatfoodcan.jpg","width":750,"height":570},{"@type":"WebSite","@id":"https:\/\/whatfoodcan.com\/#website","url":"https:\/\/whatfoodcan.com\/","name":"What Food Can","description":"What Food Can do for You","publisher":{"@id":"https:\/\/whatfoodcan.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whatfoodcan.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whatfoodcan.com\/#organization","name":"What Food Can","url":"https:\/\/whatfoodcan.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whatfoodcan.com\/#\/schema\/logo\/image\/","url":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2013\/09\/whatfoodcan-logo.png","contentUrl":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2013\/09\/whatfoodcan-logo.png","width":200,"height":200,"caption":"What Food Can"},"image":{"@id":"https:\/\/whatfoodcan.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/project\/2810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/media\/2811"}],"wp:attachment":[{"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/media?parent=2810"}],"wp:term":[{"taxonomy":"skill","embeddable":true,"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/skill?post=2810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}