{"id":5268,"date":"2017-06-17T08:25:39","date_gmt":"2017-06-17T06:25:39","guid":{"rendered":"http:\/\/whatfoodcan.com\/?post_type=project&#038;p=5268\/"},"modified":"2025-05-09T15:06:19","modified_gmt":"2025-05-09T13:06:19","slug":"chapatis-caseros","status":"publish","type":"project","link":"https:\/\/whatfoodcan.com\/es\/project\/chapatis-caseros\/","title":{"rendered":"Chapatis caseros"},"content":{"rendered":"\n<p><strong>Chapatis caseros &#8211; vegan<\/strong><\/p>\n\n\n\n<p>Chapatis caseros son quizas tus primeros intentos de hacer pan en casa. Pues s\u00ed, puedes perfectamente hacerlo. Aunque no tengas fuegos de gas o eres un principiante total. Este pan redondo sin levadura sabe delicioso y el esfuerzo extra vale la pena! Chapatis acompa\u00f1an sopas, currys, dals una ensalada, un chutney &#8211; se puede mojar en el curry, empapar en la salsa, morderlo y disfrutarlo. Y si te quedar\u00e1n restos, se pueden comer el d\u00eda siguiente, crujientes y tostados. Harina, agua caliente y aceite, no requiere m\u00e1s cosas. Mis descripciones se basan en la explicaciones de Meera Sodha del libro \u00abOriginal Indisch\u00bb y salen perfectos. As\u00ed te saldr\u00e1 bien:<\/p>\n\n\n\n<p>Para 16 chapatis (4 personas). Se puede doblar o reducir por la mitad los ingredientes, seg\u00fan lo que necesites<\/p>\n\n\n\n<p><strong>Ingredientes<\/strong><\/p>\n\n\n\n<p>450 g harina de chapati \u00abAtta\u00bb de la tienda asia. Alternative: 225 g harina integral y 225g harina tipo 405<\/p>\n\n\n\n<p>1\/2 cucharadita de sal<\/p>\n\n\n\n<p>3 cucharadas de aceite de colza<\/p>\n\n\n\n<p><strong>Preparaci\u00f3n<\/strong><\/p>\n\n\n\n<p>Mezclar la harina y la sal en un bol. Hacer una peque\u00f1a hondonada en medio de la harina y anadir 3 cucharadas de aceite de colza. Con los dedos de las manos frotar la harina y el aceite bien bien hasta que queden grumos. Entonces a\u00f1adir 250 ml de agua caliente (del grifo, no hirviendo), empezar a amasar y poco a poco a\u00f1adir otros 50 ml de agua caliente. Amasar la masa durante 6 &#8211; 8 minutos con las manos, hasta que quede suave y sedosa. Hacer una bola grande y untar la masa por fuera con un poco de aceite para que no se seque. Poner al lado.<\/p>\n\n\n\n<p>Las siguientes herramientas deber\u00edas tener preparadas: una plataforma limpia espolvoreada ligeramente con harina, un rodillo grande para la masa, un bol con un poco de harina para revolcar las bolas de chapati en ella, una sarten, y un plato para los chapatis hechos.<\/p>\n\n\n\n<p>Calentar la sarten a temperatura media alta, mas bien alta. Hacer de la masa una \u00absalchicha\u00bb larga y cortarla en 16 trozos iguales de tama\u00f1o. Hacer bolas de todos los trozos con las manos y revolcarlos en la harina dentro del bol. Ponerlos al lado.<\/p>\n\n\n\n<p>Ahora hay que hacer lo mismo para todos los chapatis: aplastarlos con la mano para que quede un pequeno \u00abdisco\u00bb, espolvorear el rollo con harina y estirar la masa hasta un diametro de unos 10 cm. Espolvorear ambos lados del chapati de nuevo con harina y estirar la masa a un tama\u00f1o de 15 cm diametro.<\/p>\n\n\n\n<p>Cuando sabes como hacerlo, puedes estirar la masa del siguiente chapati mientras se esta haciendo el primero. Pero si eres novato, mejor preparar al menos la mitad de los futuros panes. La sarten esta caliente, seca, sin grasa. Echa el primer chapati y hay que tostar el primer lado hasta que el borde quede blanco y el chapati empieza a hacer ampollas. En una cocina electrica esto puede durar 1,5 minutos, en fuegos con gas quizas 30 segundos. Girar el chapati y hacer lo mismo en el otro lado. Girar otra vez y ahora debe \u00absubir\u00bb como un pequeno balon por dentro. Esta \u00abbolsa\u00bb la aplastas suavemente con la espatula y giras el chapati. En el segundo lado haces lo mismo, sube &#8211; baja. El chapati esta listo, cuando ya no se vean partes oscuras, humedas. Entonces, no hay tiempo para chatear o ir al lavabo, hay que estar muy pendiente, es un proceso r\u00e1pido y exitante. Pon los chapatis acabados en un plato y cubre los con un pa\u00f1uelo o mete el plato en el horno para que no se enfrian. Sigue as\u00ed con todos. Ya veras que chulo y que apetitoso salen! Y si uno se quema, no pasa nada. El primer chapati normalmente no sale tan bien, porque la sarten no esta caliente caliente. Pero ya veras, a partir del segundo va mucho mejor.<\/p>\n\n\n\n<p>Es un pan muy rico y muy economico!<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"http:\/\/whatfoodcan.com\/wp-content\/uploads\/2017\/06\/IMG_0905.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"3264\" height=\"2448\" src=\"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2017\/06\/IMG_0905.jpg\" alt=\"\" class=\"wp-image-5314\" srcset=\"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2017\/06\/IMG_0905.jpg 3264w, https:\/\/whatfoodcan.com\/wp-content\/uploads\/2017\/06\/IMG_0905-300x225.jpg 300w, https:\/\/whatfoodcan.com\/wp-content\/uploads\/2017\/06\/IMG_0905-768x576.jpg 768w, https:\/\/whatfoodcan.com\/wp-content\/uploads\/2017\/06\/IMG_0905-1024x768.jpg 1024w, https:\/\/whatfoodcan.com\/wp-content\/uploads\/2017\/06\/IMG_0905-220x165.jpg 220w\" sizes=\"(max-width: 3264px) 100vw, 3264px\" \/><\/a><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":5262,"parent":0,"template":"","meta":{"_acf_changed":false},"skill":[390],"class_list":["post-5268","project","type-project","status-publish","has-post-thumbnail","hentry","skill-ayurveda-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chapatis caseros | What food can<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whatfoodcan.com\/es\/project\/chapatis-caseros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chapatis caseros | What food can\" \/>\n<meta property=\"og:description\" content=\"Chapatis caseros &#8211; vegan Chapatis caseros son quizas tus primeros intentos de hacer pan en casa. Pues s\u00ed, puedes perfectamente hacerlo. Aunque no tengas fuegos de gas o eres un principiante total. Este pan redondo sin levadura sabe delicioso y el esfuerzo extra vale la pena! Chapatis acompa\u00f1an sopas, currys, dals una ensalada, un chutney [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whatfoodcan.com\/es\/project\/chapatis-caseros\/\" \/>\n<meta property=\"og:site_name\" content=\"What Food Can\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T13:06:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2017\/06\/whatfoodcan_chapatis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3264\" \/>\n\t<meta property=\"og:image:height\" content=\"2448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/chapatis-caseros\\\/\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/chapatis-caseros\\\/\",\"name\":\"Chapatis caseros | What food can\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/chapatis-caseros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/chapatis-caseros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/whatfoodcan_chapatis.jpg\",\"datePublished\":\"2017-06-17T06:25:39+00:00\",\"dateModified\":\"2025-05-09T13:06:19+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/chapatis-caseros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/chapatis-caseros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/whatfoodcan_chapatis.jpg\",\"contentUrl\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/whatfoodcan_chapatis.jpg\",\"width\":3264,\"height\":2448},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#website\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/\",\"name\":\"What Food Can\",\"description\":\"What Food Can do for You\",\"publisher\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whatfoodcan.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#organization\",\"name\":\"What Food Can\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/whatfoodcan-logo.png\",\"contentUrl\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/whatfoodcan-logo.png\",\"width\":200,\"height\":200,\"caption\":\"What Food Can\"},\"image\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chapatis caseros | What food can","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whatfoodcan.com\/es\/project\/chapatis-caseros\/","og_locale":"es_ES","og_type":"article","og_title":"Chapatis caseros | What food can","og_description":"Chapatis caseros &#8211; vegan Chapatis caseros son quizas tus primeros intentos de hacer pan en casa. Pues s\u00ed, puedes perfectamente hacerlo. Aunque no tengas fuegos de gas o eres un principiante total. Este pan redondo sin levadura sabe delicioso y el esfuerzo extra vale la pena! Chapatis acompa\u00f1an sopas, currys, dals una ensalada, un chutney [&hellip;]","og_url":"https:\/\/whatfoodcan.com\/es\/project\/chapatis-caseros\/","og_site_name":"What Food Can","article_modified_time":"2025-05-09T13:06:19+00:00","og_image":[{"width":3264,"height":2448,"url":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2017\/06\/whatfoodcan_chapatis.jpg","type":"image\/jpeg"}],"twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/whatfoodcan.com\/es\/project\/chapatis-caseros\/","url":"https:\/\/whatfoodcan.com\/es\/project\/chapatis-caseros\/","name":"Chapatis caseros | What food can","isPartOf":{"@id":"https:\/\/whatfoodcan.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whatfoodcan.com\/es\/project\/chapatis-caseros\/#primaryimage"},"image":{"@id":"https:\/\/whatfoodcan.com\/es\/project\/chapatis-caseros\/#primaryimage"},"thumbnailUrl":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2017\/06\/whatfoodcan_chapatis.jpg","datePublished":"2017-06-17T06:25:39+00:00","dateModified":"2025-05-09T13:06:19+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whatfoodcan.com\/es\/project\/chapatis-caseros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whatfoodcan.com\/es\/project\/chapatis-caseros\/#primaryimage","url":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2017\/06\/whatfoodcan_chapatis.jpg","contentUrl":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2017\/06\/whatfoodcan_chapatis.jpg","width":3264,"height":2448},{"@type":"WebSite","@id":"https:\/\/whatfoodcan.com\/#website","url":"https:\/\/whatfoodcan.com\/","name":"What Food Can","description":"What Food Can do for You","publisher":{"@id":"https:\/\/whatfoodcan.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whatfoodcan.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whatfoodcan.com\/#organization","name":"What Food Can","url":"https:\/\/whatfoodcan.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whatfoodcan.com\/#\/schema\/logo\/image\/","url":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2013\/09\/whatfoodcan-logo.png","contentUrl":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2013\/09\/whatfoodcan-logo.png","width":200,"height":200,"caption":"What Food Can"},"image":{"@id":"https:\/\/whatfoodcan.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/project\/5268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/media\/5262"}],"wp:attachment":[{"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/media?parent=5268"}],"wp:term":[{"taxonomy":"skill","embeddable":true,"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/skill?post=5268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}