{"id":635,"date":"2014-03-10T18:32:28","date_gmt":"2014-03-10T17:32:28","guid":{"rendered":"http:\/\/whatfoodcan.com\/?post_type=project&#038;p=635"},"modified":"2025-05-08T20:29:16","modified_gmt":"2025-05-08T18:29:16","slug":"edulcorante-artificial","status":"publish","type":"project","link":"https:\/\/whatfoodcan.com\/es\/project\/edulcorante-artificial\/","title":{"rendered":"Edulcorante artificial"},"content":{"rendered":"\n<p><b>Edulcorante artificial<\/b><\/p>\n\n\n\n<p>Hay que evitar el<b> aspartamo<\/b> u otros edulcorantes. En los alimentos consta como Nutra Sweet, Canderel o simplemente como E951 y, por lo tanto, el comprador no puede identificarlo con facilidad. Esta sustancia se encuentra en muchos productos \u201clight\u201d y \u201cwellness\u201c, como en yogures, postres, chicles y bebidas diet\u00e9ticas. \u201cLight\u201c no significa autom\u00e1ticamente \u201csano\u201d.<\/p>\n\n\n\n<p>La<b> fructosa<\/b> es una sustancia natural presente en las frutas; por lo tanto, es sana. Cuando la fructosa se produce artificialmente, ya no es recomendable. No provoca una sensaci\u00f3n de saciedad, a diferencia del efecto natural propio del az\u00facar. Uno come y come, ingiere cada vez m\u00e1s calor\u00edas sin llegar a sentir esa saciedad. A corto plazo, la fructosa provoca gases y diarreas; a largo plazo, engorda y causa enfermedades. Muchos de los yogures llamados \u201cdiet\u00e9ticos\u201d con solo un 1% de grasa sugieren ser un producto bajo en calor\u00edas cuando, en realidad, contienen fructosa con sus calor\u00edas correspondientes.<\/p>\n\n\n\n<p><strong>Imortante:<\/strong> un estudio actual confirma, que edulcorantes artificiales alteran la flora intestinal y pueden llevar a la intolerancia de glucosa.* Aunque el grupo de participantes ha sido relativamente peque\u00f1o, se ha podido demostrar que los edulcorantes artificiales no tienen ning\u00fan efecto positivo en seres humanos o animales.<\/p>\n\n\n\n<p>*Sugar substitutes linked to obesity. Revista t\u00e9cnica \u00abNature\u00bb, 17.09.2014, Alison Abbott<\/p>\n\n\n\n<p><a title=\"Articulo en ingl\u00e9s online\" href=\"http:\/\/www.nature.com\/nature\/journal\/v514\/n7521\/full\/nature13793.html\">Art\u00edculo en ingl\u00e9s<\/a><\/p>\n","protected":false},"featured_media":2687,"parent":0,"template":"","meta":{"_acf_changed":false},"skill":[19],"class_list":["post-635","project","type-project","status-publish","has-post-thumbnail","hentry","skill-azucar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Edulcorante artificial | What food can<\/title>\n<meta name=\"description\" content=\"Edulcorante artificial: cuando la fructosa se produce artificialmente, ya no es recomendable. No provoca una sensaci\u00f3n de saciedad, a diferencia del\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whatfoodcan.com\/es\/project\/edulcorante-artificial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edulcorante artificial | What food can\" \/>\n<meta property=\"og:description\" content=\"Edulcorante artificial: cuando la fructosa se produce artificialmente, ya no es recomendable. No provoca una sensaci\u00f3n de saciedad, a diferencia del\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whatfoodcan.com\/es\/project\/edulcorante-artificial\/\" \/>\n<meta property=\"og:site_name\" content=\"What Food Can\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-08T18:29:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2014\/03\/Whatfoodcan_edulcorantes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/edulcorante-artificial\\\/\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/edulcorante-artificial\\\/\",\"name\":\"Edulcorante artificial | What food can\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/edulcorante-artificial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/edulcorante-artificial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/Whatfoodcan_edulcorantes.jpg\",\"datePublished\":\"2014-03-10T17:32:28+00:00\",\"dateModified\":\"2025-05-08T18:29:16+00:00\",\"description\":\"Edulcorante artificial: cuando la fructosa se produce artificialmente, ya no es recomendable. No provoca una sensaci\u00f3n de saciedad, a diferencia del\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/edulcorante-artificial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/es\\\/project\\\/edulcorante-artificial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/Whatfoodcan_edulcorantes.jpg\",\"contentUrl\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/Whatfoodcan_edulcorantes.jpg\",\"width\":750,\"height\":570},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#website\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/\",\"name\":\"What Food Can\",\"description\":\"What Food Can do for You\",\"publisher\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/whatfoodcan.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#organization\",\"name\":\"What Food Can\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/whatfoodcan-logo.png\",\"contentUrl\":\"https:\\\/\\\/whatfoodcan.com\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/whatfoodcan-logo.png\",\"width\":200,\"height\":200,\"caption\":\"What Food Can\"},\"image\":{\"@id\":\"https:\\\/\\\/whatfoodcan.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Edulcorante artificial | What food can","description":"Edulcorante artificial: cuando la fructosa se produce artificialmente, ya no es recomendable. No provoca una sensaci\u00f3n de saciedad, a diferencia del","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whatfoodcan.com\/es\/project\/edulcorante-artificial\/","og_locale":"es_ES","og_type":"article","og_title":"Edulcorante artificial | What food can","og_description":"Edulcorante artificial: cuando la fructosa se produce artificialmente, ya no es recomendable. No provoca una sensaci\u00f3n de saciedad, a diferencia del","og_url":"https:\/\/whatfoodcan.com\/es\/project\/edulcorante-artificial\/","og_site_name":"What Food Can","article_modified_time":"2025-05-08T18:29:16+00:00","og_image":[{"width":750,"height":570,"url":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2014\/03\/Whatfoodcan_edulcorantes.jpg","type":"image\/jpeg"}],"twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/whatfoodcan.com\/es\/project\/edulcorante-artificial\/","url":"https:\/\/whatfoodcan.com\/es\/project\/edulcorante-artificial\/","name":"Edulcorante artificial | What food can","isPartOf":{"@id":"https:\/\/whatfoodcan.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whatfoodcan.com\/es\/project\/edulcorante-artificial\/#primaryimage"},"image":{"@id":"https:\/\/whatfoodcan.com\/es\/project\/edulcorante-artificial\/#primaryimage"},"thumbnailUrl":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2014\/03\/Whatfoodcan_edulcorantes.jpg","datePublished":"2014-03-10T17:32:28+00:00","dateModified":"2025-05-08T18:29:16+00:00","description":"Edulcorante artificial: cuando la fructosa se produce artificialmente, ya no es recomendable. No provoca una sensaci\u00f3n de saciedad, a diferencia del","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whatfoodcan.com\/es\/project\/edulcorante-artificial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whatfoodcan.com\/es\/project\/edulcorante-artificial\/#primaryimage","url":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2014\/03\/Whatfoodcan_edulcorantes.jpg","contentUrl":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2014\/03\/Whatfoodcan_edulcorantes.jpg","width":750,"height":570},{"@type":"WebSite","@id":"https:\/\/whatfoodcan.com\/#website","url":"https:\/\/whatfoodcan.com\/","name":"What Food Can","description":"What Food Can do for You","publisher":{"@id":"https:\/\/whatfoodcan.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whatfoodcan.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/whatfoodcan.com\/#organization","name":"What Food Can","url":"https:\/\/whatfoodcan.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/whatfoodcan.com\/#\/schema\/logo\/image\/","url":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2013\/09\/whatfoodcan-logo.png","contentUrl":"https:\/\/whatfoodcan.com\/wp-content\/uploads\/2013\/09\/whatfoodcan-logo.png","width":200,"height":200,"caption":"What Food Can"},"image":{"@id":"https:\/\/whatfoodcan.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/project\/635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/types\/project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/media\/2687"}],"wp:attachment":[{"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/media?parent=635"}],"wp:term":[{"taxonomy":"skill","embeddable":true,"href":"https:\/\/whatfoodcan.com\/es\/wp-json\/wp\/v2\/skill?post=635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}